{"id":44,"date":"2023-05-26T06:39:40","date_gmt":"2023-05-26T06:39:40","guid":{"rendered":"https:\/\/www.alcoawheels.com\/europe\/fr\/?page_id=44"},"modified":"2025-02-10T15:54:08","modified_gmt":"2025-02-10T14:54:08","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","title":{"rendered":"Questions fr\u00e9quemment pos\u00e9es \/ FAQ"},"content":{"rendered":"\n<div class=\"wp-block-alcoa-wheels-hero-banner-innerpage hero-banner with-image layout-2 overlayEnable align- vertical-align- align-center vertical-align-center\" style=\"background-color:#eee\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg\" alt=\"Frequently Asked Questions Alcoa Wheels\" class=\"responsiveImage\"\/><div class=\"hero-banner__header\" style=\"text-align:center\"><div class=\"container\"><h1 class=\"hero-banner__header--title\">Questions Fr\u00e9quemment Pos\u00e9es<\/h1><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion accordion-sections\" style=\"max-width:970px\"><h4>LES R\u00c9PONSES \u00c0 VOS QUESTIONS.<\/h4><div class=\"accordion-items\">\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q1. Je voudrais plus d&#8217;informations concernant vos produits, ainsi que des d\u00e9tails techniques.<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Les informations techniques peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es dans la section&nbsp;<a href=\"\/europe\/fr\/documents-produit\">T\u00e9l\u00e9chargements<\/a>.<\/p>\n\n\n\n<p>Rendez-vous sur la page de&nbsp;<a href=\"\/europe\/fr\/contact\">Contact<\/a><a href=\"https:\/\/www.alcoawheels.com\/alcoawheels\/europe\/fr\/contact.asp\">&nbsp;<\/a>pour entrer en contact avec l&#8217;un de nos Responsables des roues ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q2. Je souhaite acheter des roues ALCOA<sup>\u00ae<\/sup> WHEELS. Qui dois-je contacter ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Pour toute question, contactez votre distributeur de roues ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS r\u00e9pertori\u00e9&nbsp;<a href=\"\/europe\/fr\/ou-acheter\">ici<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q3. Puis-je obtenir une roue de rechange, lorsque j&#8217;envoie une r\u00e9clamation au Fleet Service Center ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Non, le Fleet Service Center n&#8217;offre pas de roues de rechange.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q4. Combien de temps faut-il pour que la nouvelle roue arrive ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Une fois votre r\u00e9clamation accept\u00e9e, une nouvelle roue vous sera envoy\u00e9e. Le d\u00e9lai d\u00e9pend de diff\u00e9rents facteurs tels que le lieu, le type de roue et le planning de production de notre usine. Contactez le Fleet Service Center par e-mail&nbsp;(<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>) ou par t\u00e9l\u00e9phone (<img loading=\"lazy\" decoding=\"async\" width=\"14\" height=\"13\" class=\"wp-image-240\" style=\"width: 14px;\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/phone-icon.4e773c4f.png\" alt=\"\"> <a href=\"tel:+36-22-531841\">+36-22-531841<\/a>&nbsp;du lundi au vendredi : 8h00-16h30 CET) pour vous renseigner sur l&#8217;\u00e9tat d&#8217;avancement.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q5. J&#8217;ai des roues Alcoa Dura-Bright<sup>\u00ae<\/sup>. Comment pr\u00e9server leur brillance ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Parcourez nos&nbsp;<a href=\"https:\/\/www.alcoawheels.com\/alcoawheels\/europe\/fr\/pdf\/Alcoa_Wheels_Cleaning_FR.pdf\">instructions de nettoyage<\/a>&nbsp;et visionnez notre&nbsp;<a href=\"https:\/\/www.youtube.com\/embed\/2MPveLjZXug\">vid\u00e9o<\/a>. Howmet propose \u00e9galement une large gamme d&#8217;accessoires de la marque ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS. Consultez notre&nbsp;<a href=\"https:\/\/www.alcoawheels.com\/alcoawheels\/europe\/fr\/pdf\/Alcoa_accessory_products_FR.pdf\">brochure&nbsp;<\/a>pour plus de d\u00e9tails.<\/p>\n\n\n\n<p>Les produits de nettoyage et d&#8217;entretien ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS peuvent \u00eatre achet\u00e9s aupr\u00e8s de l&#8217;un de nos distributeurs ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS r\u00e9pertori\u00e9s&nbsp;<a href=\"\/europe\/fr\/ou-acheter\">ici<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q6. J&#8217;ai une roue Alcoa<sup>\u00ae<\/sup> Wheel en finition Bross\u00e9e pr\u00e9sentant des taches sur sa surface. Puis-je faire une demande de retour de roue pour cela ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Non, le Fleet Service Center n&#8217;acceptera pas cette r\u00e9clamation. Ce type de probl\u00e8me ne sera examin\u00e9 que si la roue a un traitement de surface Dura-Bright<sup>\u00ae<\/sup>.<\/p>\n\n\n\n<p>Pour de plus amples informations concernant l&#8217;entretien, t\u00e9l\u00e9chargez notre&nbsp;<a href=\"https:\/\/www.alcoawheels.com\/alcoawheels\/europe\/fr\/pdf\/Alcoa_Wheels_Cleaning_FR.pdf\">d\u00e9pliant sur le nettoyage<\/a>. Les produits de nettoyage et d&#8217;entretien ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS peuvent \u00eatre achet\u00e9s aupr\u00e8s de l&#8217;un de nos distributeurs ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS r\u00e9pertori\u00e9s&nbsp;<a href=\"\/europe\/fr\/ou-acheter\">ici<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q7. Je ne trouve pas le marquage\/la date de production.<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Veuillez regarder la zone indiqu\u00e9e sur l\u2019image, se trouvant toujours \u00e0 l\u2019extr\u00eame oppos\u00e9 de la valve. La date de marquage (MMJJAA) est un num\u00e9ro \u00e0 6&nbsp;chiffres. Les deux premiers chiffres indiquent le mois, les deux suivants le jour et les deux derniers l&#8217;ann\u00e9e. L&#8217;exemple ci-joint pr\u00e9sente ainsi une roue produite le 30&nbsp;ao\u00fbt 2017.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"337\" src=\"https:\/\/www.alcoawheels.com\/europe\/en\/wp-content\/uploads\/sites\/8\/2023\/05\/Rollstamp-mod.jpg?w=450\" alt=\"\" class=\"wp-image-256\" style=\"width:338px;height:253px\" srcset=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/Rollstamp-mod.jpg 450w, https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/Rollstamp-mod.jpg?resize=300,225 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q8. Je ne parviens pas \u00e0 envoyer ma r\u00e9clamation. Le formulaire de d\u00e9claration n&#8217;accepte pas les donn\u00e9es que j&#8217;ai communiqu\u00e9es.<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Contactez le Fleet Service Center par e-mail&nbsp;(<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>)&nbsp;ou par t\u00e9l\u00e9phone (<img loading=\"lazy\" decoding=\"async\" width=\"14\" height=\"13\" class=\"wp-image-240\" style=\"width: 14px;\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/phone-icon.4e773c4f.png\" alt=\"\"> <a href=\"tel:+36-22-531841\">+36-22-531841<\/a>&nbsp;du lundi au vendredi : 8h00-16h30 CET) pour de l&#8217;assistance.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q9. Je ne re\u00e7ois pas de confirmation apr\u00e8s avoir enregistr\u00e9 ma r\u00e9clamation. Que faire ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Consultez d&#8217;abord votre bo\u00eete de r\u00e9ception, ainsi que les dossiers d&#8217;e-mails ind\u00e9sirables. La confirmation devrait avoir \u00e9t\u00e9 envoy\u00e9e \u00e0 l&#8217;adresse e-mail avec laquelle vous vous \u00eates enregistr\u00e9. Si vous ne la trouvez toujours pas, contactez le Fleet Service Center par e-mail&nbsp;(<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>), afin qu\u2019un de nos collaborateurs puissent v\u00e9rifier le statut de transmission.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q10. Le ticket DHL n&#8217;est pas arriv\u00e9 dans les 5 jours pr\u00e9vus. Que dois-je faire ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Consultez d&#8217;abord votre bo\u00eete de r\u00e9ception, ainsi que les dossiers d&#8217;e-mails ind\u00e9sirables. La confirmation devrait avoir \u00e9t\u00e9 envoy\u00e9e \u00e0 l&#8217;adresse e-mail avec laquelle vous vous \u00eates enregistr\u00e9. Si vous ne la trouvez toujours pas, contactez le Fleet Service Center par e-mail&nbsp;(<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>) ou par t\u00e9l\u00e9phone (<img loading=\"lazy\" decoding=\"async\" width=\"14\" height=\"13\" class=\"wp-image-240\" style=\"width: 14px;\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/phone-icon.4e773c4f.png\" alt=\"\"> <a href=\"tel:+36-22-531841\">+36-22-531841<\/a>&nbsp;du lundi au vendredi : 8h00-16h30 CET).<\/p>\n\n\n\n<p>Remarque! N&#8217;utilisez jamais des documents d&#8217;exp\u00e9dition \u00e9crits \u00e0 la main. Utilisez uniquement les \u00e9tiquettes \u00e9lectroniques fournies par DHL. En cas de probl\u00e8me, contactez le Fleet Service Center par e-mail (<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>) ou par t\u00e9l\u00e9phone (<img loading=\"lazy\" decoding=\"async\" width=\"14\" height=\"13\" class=\"wp-image-240\" style=\"width: 14px;\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/phone-icon.4e773c4f.png\" alt=\"\"> <a href=\"tel:+36-22-531841\">+36-22-531841<\/a>&nbsp;du lundi au vendredi : 8h00-16h30 CET).<\/p>\n\n\n\n<p>&lt;&lt;Document d&#8217;exp\u00e9dition DHL correct&gt;&gt;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"475\" height=\"791\" src=\"https:\/\/www.alcoawheels.com\/europe\/en\/wp-content\/uploads\/sites\/8\/2023\/05\/DHL.png?w=475\" alt=\"\" class=\"wp-image-257\" style=\"width:356px;height:593px\" srcset=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/DHL.png 475w, https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/DHL.png?resize=180,300 180w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q11. DHL n&#8217;est pas encore venu enlever ma roue. Que dois-je faire ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>V\u00e9rifiez d&#8217;abord si vous avez re\u00e7u le document d&#8217;exp\u00e9dition \u00e9lectronique fourni par DHL. Celui-ci a \u00e9t\u00e9 envoy\u00e9 \u00e0 l&#8217;adresse e-mail avec laquelle vous vous \u00eates enregistr\u00e9. N&#8217;oubliez pas de consulter \u00e9galement les dossiers d&#8217;e-mails ind\u00e9sirables. Appelez le num\u00e9ro DHL r\u00e9gional indiqu\u00e9 sur le document, afin de vous informer du statut de l\u2019enl\u00e8vement. Mentionnez le num\u00e9ro de r\u00e9f\u00e9rence DHL fourni dans l&#8217;e-mail.<\/p>\n\n\n\n<p><em>Remarque! Imprimez le formulaire de ticket ALCOA<sup>\u00ae<\/sup>&nbsp;WHEELS et collez-le correctement sur l&#8217;emballage de la roue avant l&#8217;enl\u00e8vement. \u00c9vitez les documents \u00e9crits \u00e0 la main. Si ce n&#8217;est pas possible, choisissez le service \u00ab&nbsp;Economy select&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<p>Si vous n&#8217;avez re\u00e7u aucune confirmation, contactez le Fleet Service Center par e-mail&nbsp;(<a href=\"mailto:fleet@howmet.com\">fleet@howmet.com<\/a>) ou par t\u00e9l\u00e9phone (<img loading=\"lazy\" decoding=\"async\" width=\"14\" height=\"13\" class=\"wp-image-240\" style=\"width: 14px;\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/phone-icon.4e773c4f.png\" alt=\"\"> <a href=\"tel:+36-22-531841\">+36-22-531841<\/a>&nbsp;du lundi au vendredi : 8h00-16h30 CET).<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q12 Comment puis-je savoir si ma demande a \u00e9t\u00e9 accept\u00e9e ou rejet\u00e9e ? Comment puis-je connaitre le statut de ma demande en garantie ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p><a href=\"https:\/\/www.alcoawheels.com\/europe\/fr\/suivi-du-statut-du-formulaire-de-retour-de-roue\/\">Veuillez utiliser le suivi du statut de votre demande<\/a> pour obtenir l&#8217;\u00e9tat actuel de votre r\u00e9clamation, en saisissant l&#8217;identifiant unique (ID en objet de la confirmation d&#8217;enregistrement) et l&#8217;adresse \u00e9lectronique que vous avez renseign\u00e9.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q13. Comment puis-je savoir quand la roue de remplacement va arriver ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Nous vous enverrons les informations d&#8217;exp\u00e9dition de DHL \u00e0 l&#8217;adresse e-mail avec laquelle vous vous \u00eates enregistr\u00e9. Vous obtiendrez alors un lien vous permettant de suivre le processus \u00e0 tout moment.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q14. Ma roue a \u00e9t\u00e9 refus\u00e9e. Me sera-t-elle automatiquement renvoy\u00e9e ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Non, le Fleet Service Center ne renverra pas et ne remboursera pas la livraison ou les roues refus\u00e9es. Vous pouvez toutefois organiser par vous-m\u00eame un enl\u00e8vement de la roue, afin que celle-ci soit retourn\u00e9e \u00e0 vos propres frais. La roue restera dans notre \u00e9tablissement pendant 14&nbsp;jours calendaires, \u00e0 compter de la date de cr\u00e9ation du rapport de garantie. Une fois les 14&nbsp;jours calendaires pass\u00e9s, il ne sera plus possible d&#8217;organiser un enl\u00e8vement et la roue sera d\u00e8s lors recycl\u00e9e.<\/p>\n\n\n\n<p>Les roues peuvent \u00eatre enlev\u00e9es \u00e0 l&#8217;adresse suivante&nbsp;:<\/p>\n\n\n\n<p>Howmet-K\u00f6f\u00e9m Ltd.&nbsp;: Verseci u. 1-15 &#8211; H-8000 Sz\u00e9kesfeh\u00e9rv\u00e1r &#8211; HONGRIE<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q15. Ma roue concern\u00e9e est \u00e9quip\u00e9e d&#8217;une valve TPMS et d&#8217;un capteur TPMS \/ toute autre type de syst\u00e8me TPMS, celui-ci sera-t-il \u00e9galement remplac\u00e9 ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Non, si la demande en garantie concernant la roue est accept\u00e9e, le Centre de Service aux Flottes (FSC) ne renverra, ni ne remplacera, aucune pi\u00e8ce li\u00e9e au syst\u00e8me TPMS ou autre.<\/p>\n\n\n\n<p>Il est ainsi recommand\u00e9 de d\u00e9monter toute valve, valve pour TPMS, capteur TPMS et autre pi\u00e8ce fix\u00e9e sur la roue.<\/p>\n\n\n\n<p>La nouvelle roue de remplacement, qui vous sera retourn\u00e9e, sera \u00e9quip\u00e9e d\u2019une valve standard mont\u00e9e dessus.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-accordion-item accordion-item-sections\"><p class=\"accordion-header\">Q16. O\u00f9 puis-je suivre l&#8217;\u00e9tat d&#8217;avancement de l&#8217;enregistrement de ma roue ?<\/p><div class=\"accordion-content\" data-anchor=\"\">\n<p>Le statut de votre formulaire d&#8217;enregistrement de roue peut \u00eatre v\u00e9rifi\u00e9 sur le Suivi du statut du formulaire d&#8217;enregistrement de roue .<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer spacer-fifty\"><\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-card-usecase-1 card-box-v1__body with-icon align-center vertical-align-center\" id=\"card_box_v1-6cd0cba0-9024-4f15-a63c-a6335c0b9207\"><div class=\"fullwidthcontainer\"><div class=\"card-box-v1__boxes has-4-columns\"><div class=\"card-box-v1__box  with-link \" style=\"background-color:#00afb9\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"Contactez-nous\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"171\" height=\"171\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/contact.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">Contactez-nous<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/contact\" aria-label=\"Contactez-nous\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#34bfc7\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"Gamme de roues\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/product-search.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">Gamme de roues<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/gamme-de-roues\" aria-label=\"Gamme de roues\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#00afb9\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"O\u00f9 acheter?\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/where-to-buy.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">O\u00f9 acheter?<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/ou-acheter\" aria-label=\"O\u00f9 acheter?\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#34bfc7\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"T\u00e9l\u00e9chargements\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/product-literature.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">T\u00e9l\u00e9chargements<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/documents-produit\" aria-label=\"T\u00e9l\u00e9chargements\"><\/a><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":44,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"protected_reviewer_email":"","editor_notices":[],"footnotes":""},"class_list":["post-44","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FAQ | Alcoa Wheels<\/title>\n<meta name=\"description\" content=\"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Questions fr\u00e9quemment pos\u00e9es \/ FAQ\" \/>\n<meta property=\"og:description\" content=\"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe French\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T14:54:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/\",\"name\":\"FAQ | Alcoa Wheels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/06\\\/faq-banner.jpeg\",\"datePublished\":\"2023-05-26T06:39:40+00:00\",\"dateModified\":\"2025-02-10T14:54:08+00:00\",\"description\":\"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/06\\\/faq-banner.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/06\\\/faq-banner.jpeg\",\"width\":1119,\"height\":280,\"caption\":\"Frequently Asked Questions Alcoa Wheels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions fr\u00e9quemment pos\u00e9es \\\/ FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\",\"name\":\"Europe French\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#organization\",\"name\":\"Europe French\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/05\\\/logo-black.gif\",\"contentUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/05\\\/logo-black.gif\",\"width\":71,\"height\":64,\"caption\":\"Europe French\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FAQ | Alcoa Wheels","description":"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","og_locale":"en_US","og_type":"article","og_title":"Questions fr\u00e9quemment pos\u00e9es \/ FAQ","og_description":"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.","og_url":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","og_site_name":"Europe French","article_modified_time":"2025-02-10T14:54:08+00:00","og_image":[{"url":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","name":"FAQ | Alcoa Wheels","isPartOf":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/#primaryimage"},"image":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg","datePublished":"2023-05-26T06:39:40+00:00","dateModified":"2025-02-10T14:54:08+00:00","description":"Questions fr\u00e9quemment pos\u00e9es \u00e0 propos des roues Alcoa\u00ae Wheels.","breadcrumb":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/#primaryimage","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg","contentUrl":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/faq-banner.jpeg","width":1119,"height":280,"caption":"Frequently Asked Questions Alcoa Wheels"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alcoawheels.com\/europe\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions fr\u00e9quemment pos\u00e9es \/ FAQ"}]},{"@type":"WebSite","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#website","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/","name":"Europe French","description":"","publisher":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alcoawheels.com\/europe\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#organization","name":"Europe French","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/logo-black.gif","contentUrl":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/logo-black.gif","width":71,"height":64,"caption":"Europe French"},"image":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/alcoawheels.com\/europe\/fr\/faq\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Questions fr\u00e9quemment pos\u00e9es \/ FAQ","url":"http:\/\/www.alcoawheels.com\/europe\/fr\/faq\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.alcoawheels.com\/europe\/fr\/faq\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"howmet"}],"creator":["howmet"],"publisher":{"@type":"Organization","name":"Europe French","logo":""},"keywords":[],"dateCreated":"2023-05-26T06:39:40Z","datePublished":"2023-05-26T06:39:40Z","dateModified":"2025-02-10T14:54:08Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"WebPage\",\"headline\":\"Questions fr\\u00e9quemment pos\\u00e9es \\\/ FAQ\",\"url\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/faq\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"howmet\"}],\"creator\":[\"howmet\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Europe French\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-05-26T06:39:40Z\",\"datePublished\":\"2023-05-26T06:39:40Z\",\"dateModified\":\"2025-02-10T14:54:08Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/alcoawheels.com\/p.js"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":13,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":3822,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/44\/revisions\/3822"}],"wp:attachment":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}