{"id":66,"date":"2023-05-26T06:43:04","date_gmt":"2023-05-26T06:43:04","guid":{"rendered":"https:\/\/www.alcoawheels.com\/europe\/fr\/?page_id=66"},"modified":"2023-08-24T10:48:03","modified_gmt":"2023-08-24T08:48:03","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","title":{"rendered":"Avis juridique"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer spacer-fifty\"><\/div>\n\n\n\n<div class=\"wp-block-columns padded-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-mentions-legales-en-ligne-de-howmet-aerospace\">Mentions l\u00e9gales en ligne de Howmet Aerospace<\/h3>\n\n\n\n<p>Howmet Aerospace Inc. et ses filiales et soci\u00e9t\u00e9s affili\u00e9es (ci-apr\u00e8s, collectivement \u00ab&nbsp;Howmet Aerospace&nbsp;\u00bb) maintiennent ce site Web \u00e0 des fins d&#8217;information, d&#8217;\u00e9ducation et de communication. Sauf indication contraire, vous pouvez t\u00e9l\u00e9charger le mat\u00e9riel affich\u00e9 sur ce site Web pour un usage non commercial et personnel uniquement, \u00e0 condition que vous conserviez \u00e9galement tous les avis de droits d&#8217;auteur et autres avis de propri\u00e9t\u00e9 figurant sur les mat\u00e9riels. Vous ne pouvez cependant pas diffuser, modifier, transmettre, r\u00e9utiliser, republier ou utiliser le contenu de ce site Web \u00e0 des fins publiques ou commerciales, y compris des donn\u00e9es, textes, images, \u00e9l\u00e9ments audio ou vid\u00e9o, sans l&#8217;autorisation \u00e9crite pr\u00e9alable de Howmet Aerospace. Certaines sections de ce site Web peuvent contenir des restrictions suppl\u00e9mentaires d&#8217;utilisation ou d&#8217;acc\u00e8s. L&#8217;utilisation de ce site Web et l&#8217;acc\u00e8s au mat\u00e9riel qu&#8217;il contient sont soumis aux conditions g\u00e9n\u00e9rales suivantes, ainsi qu&#8217;\u00e0 toutes les lois applicables. Votre acc\u00e8s et votre utilisation de ce site Web constituent votre pleine acceptation de ces conditions g\u00e9n\u00e9rales<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Sauf indication contraire, tous les \u00e9l\u00e9ments de ce site Web sont prot\u00e9g\u00e9s par le droit d&#8217;auteur. Ils ne peuvent \u00eatre utilis\u00e9s qu&#8217;avec l&#8217;autorisation \u00e9crite pr\u00e9alable de Howmet Aerospace, comme indiqu\u00e9 dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales ou dans le texte de ce site Web. Howmet Aerospace ne garantit pas que votre utilisation des informations ou des \u00e9l\u00e9ments graphiques affich\u00e9s sur ce site Web ne violera pas les droits de tiers qui ne sont pas li\u00e9s \u00e0 Howmet Aerospace. Toute question concernant le mat\u00e9riel prot\u00e9g\u00e9 par le droit d&#8217;auteur sur ce site Web doit \u00eatre adress\u00e9e \u00e0 l&#8217;adresse e-mail suivante&nbsp;:&nbsp;<a href=\"mailto:howmet-editor@howmet.com\">howmet-editor@howmet.com<\/a>.<\/li>\n\n\n\n<li>Les informations sur ce site Web peuvent contenir des inexactitudes techniques ou des erreurs typographiques. Les informations peuvent \u00eatre modifi\u00e9es ou mises \u00e0 jour sans que vous en soyez averti(e). Howmet Aerospace peut \u00e9galement apporter des am\u00e9liorations et\/ou des changements aux produits d\u00e9crits dans ces informations \u00e0 tout moment et sans pr\u00e9avis.<\/li>\n\n\n\n<li>Tout ce qui se trouve sur ce site Web vous est fourni \u00ab&nbsp;EN L&#8217;\u00c9TAT&nbsp;\u00bb SANS GARANTIE D&#8217;AUCUNE SORTE, EXPRESSE OU IMPLICITE, Y COMPRIS, MAIS SANS S&#8217;Y LIMITER, LES GARANTIES IMPLICITES DE QUALIT\u00c9 MARCHANDE, D&#8217;AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER OU DE NON-CONTREFA\u00c7ON. CERTAINES JURIDICTIONS NE PERMETTENT PAS L&#8217;EXCLUSION DE GARANTIES IMPLICITES, PAR CONS\u00c9QUENT, LA CLAUSE DE NON-RESPONSABILIT\u00c9 CI-DESSUS PEUT NE PAS S&#8217;APPLIQUER \u00c0 VOUS.<\/li>\n\n\n\n<li>Howmet Aerospace n&#8217;assume aucune responsabilit\u00e9 et ne sera pas responsable de tout dommage ou virus qui pourrait infecter votre \u00e9quipement informatique ou autre bien, en raison de votre acc\u00e8s, de votre utilisation ou de votre navigation sur ce site Web ou de votre t\u00e9l\u00e9chargement de tout mat\u00e9riel, donn\u00e9es, texte, images, vid\u00e9o ou son.<\/li>\n\n\n\n<li>Howmet Aerospace ne fait aucune d\u00e9claration concernant tout autre site Web tiers auquel vous pourriez acc\u00e9der via celui-ci. Lorsque vous acc\u00e9dez \u00e0 un site Web tiers, vous devez comprendre qu&#8217;il est ind\u00e9pendant de Howmet Aerospace et que Howmet Aerospace n&#8217;a aucun contr\u00f4le sur le contenu de ce site Web. De plus, un lien vers un site Web n&#8217;appartenant pas \u00e0 Howmet Aerospace ne signifie pas que Howmet Aerospace endosse ou accepte une quelconque responsabilit\u00e9, quant au contenu ou \u00e0 l&#8217;utilisation de ce site Web. EN AUCUN CAS, Howmet Aerospace NE SERA TENUE RESPONSABLE ENVERS UNE QUELCONQUE PARTIE DE DOMMAGES DIRECTS, INDIRECTS, ACCESSOIRES, PUNITIFS, SP\u00c9CIAUX OU AUTRES DOMMAGES INDIRECTS, QUE CE SOIT POUR UNE UTILISATION DE CE SITE WEB OU DE TOUT AUTRE SITE WEB RELI\u00c9 PAR UN HYPERLIEN, Y COMPRIS, SANS LIMITATION, TOUTE PERTE DE PROFITS, INTERRUPTION DES ACTIVIT\u00c9S, PERTE DE PROGRAMMES OU D&#8217;AUTRES DONN\u00c9ES SUR VOTRE SYST\u00c8ME DE TRAITEMENT DES INFORMATIONS OU AUTREMENT, M\u00caME SI Howmet Aerospace EST EXPRESS\u00c9MENT AVIS\u00c9E DE LA POSSIBILIT\u00c9 DE TELS DOMMAGES.<\/li>\n\n\n\n<li>Howmet Aerospace ne souhaite pas recevoir d&#8217;informations confidentielles ou exclusives de votre part via ce site Web. Veuillez noter que toute information ou tout mat\u00e9riel envoy\u00e9s \u00e0 Howmet Aerospace via un lien fourni sur ce site Web seront consid\u00e9r\u00e9s comme NON confidentiels. En envoyant ainsi \u00e0 Howmet Aerospace tout(e) information ou mat\u00e9riel, vous accordez irr\u00e9vocablement \u00e0 Howmet Aerospace une licence mondiale illimit\u00e9e pour utiliser, distribuer, afficher, reproduire, ex\u00e9cuter, modifier et transmettre ces mat\u00e9riaux ou informations, et vous acceptez \u00e9galement que Howmet Aerospace sera libre d\u2019utiliser les id\u00e9es, concepts, savoir-faire ou techniques que vous nous transmettez \u00e0 quelque fin que ce soit. Si vous souhaitez que vos informations confidentielles ou exclusives soient prises en compte par Howmet Aerospace, vous devrez d&#8217;abord signer un accord de non-confidentialit\u00e9 avant que les informations ne soient consult\u00e9es par un technicien de Howmet Aerospace. Pour obtenir un accord de non-confidentialit\u00e9, \u00e9crivez \u00e0 IPLD &#8211; Unsolicited Ideas, Howmet Aerospace Communications Department, 201 Isabella Street, Suite 200, Pittsburgh, PA 15212.<\/li>\n\n\n\n<li>Sur l\u2019ensemble de ce site Web, vous trouverez un certain nombre de marques de commerce, de logos et de marques de service (collectivement les \u00ab&nbsp;Marques&nbsp;\u00bb). Les marques sont des marques d\u00e9pos\u00e9es et non d\u00e9pos\u00e9es de Howmet Aerospace et autres. Lorsqu\u2019elles sont suivies du signe \u00ab&nbsp;\u00ae&nbsp;\u00bb, elles sont des marques d\u00e9pos\u00e9es aux \u00c9tats-Unis&nbsp;; tous les autres sont des marques d\u00e9pos\u00e9es aux \u00c9tats-Unis ou dans des pays \u00e9trangers. Rien de ce qui est contenu sur ce site Web ne doit \u00eatre interpr\u00e9t\u00e9 comme accordant une licence ou un droit d&#8217;utiliser une telle marque affich\u00e9e sur le site Web, sans l&#8217;autorisation \u00e9crite de Howmet Aerospace ou d&#8217;un tiers qui peut poss\u00e9der les marques affich\u00e9es. Toute question concernant l&#8217;utilisation des marques ou la question de savoir si un nom est en fait une marque de commerce de Howmet Aerospace doit \u00eatre adress\u00e9e \u00e0 l&#8217;adresse e-mail suivante&nbsp;:&nbsp;<a href=\"mailto:howmet-editor@howmet.com\">howmet-editor@howmet.com<\/a>.<\/li>\n\n\n\n<li>Howmet Aerospace se r\u00e9serve le droit de changer ou de modifier l&#8217;une quelconque de ces Conditions g\u00e9n\u00e9rales, \u00e0 tout moment et \u00e0 sa seule discr\u00e9tion. Tout changement ou modification entrera en vigueur d\u00e8s la publication des r\u00e9visions sur ce site Web. Votre utilisation continue de ce site Web apr\u00e8s l&#8217;affichage de ces changements ou modifications vaudra acceptation de votre part de ces changements ou modifications.<\/li>\n<\/ol>\n\n\n\n<div id=\"alcoa-wheels-buttons-75c90999-8b58-42ac-9690-eafaad76988c\" class=\"wp-block-alcoa-wheels-button-group alcoa-wheels-buttons\"><div class=\"button-row\"><div class=\"button-item\" button-item=\"0\"><p class=\"btn-main btn-link-pdf\"><a href=\"\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/howmet-european-legal-entities.pdf\">View European Legal Entities<\/a><\/p><\/div><div class=\"button-item\" button-item=\"1\"><p class=\"btn-main btn-link-pdf\"><a href=\"\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/uk-slavery-and-human-trafficking-statement.pdf\">UK Slavery and Human Trafficking Statement<\/a><\/p><\/div><div class=\"button-item\" button-item=\"2\"><p class=\"btn-main btn-link-pdf\"><a href=\"\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/California-Transparency-in-Supply-Chains-Act-Statement.pdf\">California Transparency in Supply Chains Act Statement<\/a><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-declarations-prospectives\">D\u00e9clarations prospectives<\/h3>\n\n\n\n<p>Certaines d\u00e9clarations de Howmet Aerospace Inc. sur ce site Web concernent des \u00e9v\u00e9nements et des attentes futurs et constituent \u00e0 ce titre des d\u00e9clarations prospectives, au sens de la loi Private Securities Litigation Reform Act de 1995. Les d\u00e9clarations prospectives comprennent celles contenant des mots tels que \u00ab&nbsp;anticipe&nbsp;\u00bb, \u00ab&nbsp;croit&nbsp;\u00bb, \u00ab&nbsp;pourrait&nbsp;\u00bb, \u00ab&nbsp;estime&nbsp;\u00bb, \u00ab&nbsp;pr\u00e9voit&nbsp;\u00bb, \u00ab&nbsp;planifie&nbsp;\u00bb, \u00ab&nbsp;objectif&nbsp;\u00bb, \u00ab&nbsp;orientation&nbsp;\u00bb, \u00ab&nbsp;entend&nbsp;\u00bb, \u00ab&nbsp;peut&nbsp;\u00bb, \u00ab&nbsp;perspectives&nbsp;\u00bb, \u00ab&nbsp;planifie&nbsp;\u00bb, \u00ab&nbsp;projette&nbsp;\u00bb, \u00ab&nbsp;cherche&nbsp;\u00bb, \u00ab&nbsp;voit&nbsp;\u00bb, \u00ab&nbsp;devrait&nbsp;\u00bb, \u00ab&nbsp;cible&nbsp;\u00bb, \u00ab&nbsp;voudra&nbsp;\u00bb, \u00ab&nbsp;serait&nbsp;\u00bb ou d\u2019autres mots ayant un sens similaire. Toutes les d\u00e9clarations qui refl\u00e8tent les attentes, hypoth\u00e8ses ou projections de Howmet Aerospace concernant l\u2019avenir, en dehors des d\u00e9clarations de faits historiques, sont des d\u00e9clarations prospectives, notamment s\u2019agissant des d\u00e9clarations, des pr\u00e9visions et des perspectives relatives \u00e0 l\u2019\u00e9tat des march\u00e9s finaux&nbsp;; des futurs r\u00e9sultats financiers ou rendements op\u00e9rationnels&nbsp;; des futures actions strat\u00e9giques&nbsp;; des strat\u00e9gies, pr\u00e9visions, et perspectives commerciales et financi\u00e8res de Howmet Aerospace&nbsp;; et des futurs rachats de dettes ou de titres de participation. Ces d\u00e9clarations refl\u00e8tent des croyances et des hypoth\u00e8ses fond\u00e9es sur la perception par Howmet Aerospace des tendances historiques, des conditions actuelles et des d\u00e9veloppements futurs attendus, ainsi que d\u2019autres facteurs que Howmet Aerospace estime appropri\u00e9s dans les circonstances. Les d\u00e9clarations prospectives ne sont pas des garanties de performances futures et sont soumises \u00e0 des risques, des incertitudes et des changements de circonstances difficiles \u00e0 pr\u00e9voir, qui pourraient faire en sorte que les r\u00e9sultats r\u00e9els diff\u00e8rent sensiblement de ceux indiqu\u00e9s par ces d\u00e9clarations. Ces risques et incertitudes comprennent notamment&nbsp;: (a) la d\u00e9t\u00e9rioration g\u00e9n\u00e9rale des conditions du secteur \u00e9conomique et financier mondial ; (b)&nbsp;les changements ayant un impact n\u00e9gatif sur les march\u00e9s desservis par Howmet Aerospace&nbsp;; (c)&nbsp;l\u2019impact des cyberattaques potentielles et des \u00e9ventuelles violations des technologies de l\u2019information et de la s\u00e9curit\u00e9 des donn\u00e9es&nbsp;; (d)&nbsp;la perte de clients importants ou les changements ayant un impact n\u00e9gatif sur les activit\u00e9s ou la situation financi\u00e8re des clients&nbsp;; (e)&nbsp;les probl\u00e8mes de fabrication ou autres ayant un impact sur les performances, la qualit\u00e9 ou la s\u00e9curit\u00e9 d\u2019un produit&nbsp;; (f)&nbsp;l\u2019incapacit\u00e9 des fournisseurs \u00e0 respecter leurs obligations en raison de perturbations de la cha\u00eene d\u2019approvisionnement ou d\u2019autres causes&nbsp;; (g)&nbsp;l\u2019impossibilit\u00e9 d\u2019attirer et de conserver de la main-d\u2019\u0153uvre qualifi\u00e9e et des employ\u00e9s essentiels&nbsp;; (h)&nbsp;\u2019l\u2019incertitude quant \u00e0 la dur\u00e9e, l\u2019\u00e9tendue et l\u2019impact de la pand\u00e9mie de COVID-19 sur les activit\u00e9s, les r\u00e9sultats d\u2019exploitation et la situation financi\u00e8re de Howmet Aerospace&nbsp;; \u2019\u2019\u2019\u2019\u2019\u2019\u2019\u2019(i)&nbsp;l\u2019incapacit\u00e9 \u00e0 g\u00e9n\u00e9rer une croissance des revenus, des fonds de tr\u00e9sorerie, des plans de restructuration, des r\u00e9ductions de co\u00fbts, une am\u00e9lioration de la rentabilit\u00e9 et un renforcement de la comp\u00e9titivit\u00e9 et des op\u00e9rations pr\u00e9vues ou cibl\u00e9es&nbsp;; (j)&nbsp;l\u2019incapacit\u00e9 de r\u00e9pondre \u00e0 l\u2019augmentation de la demande, aux objectifs de production ou aux engagements&nbsp;; (k)&nbsp;la concurrence des nouvelles offres de produits, des technologies de rupture ou d\u2019autres d\u00e9veloppements&nbsp;; (l)&nbsp;les risques g\u00e9opolitiques, \u00e9conomiques et r\u00e9glementaires li\u00e9s aux op\u00e9rations mondiales de Howmet Aerospace, notamment s\u2019agissant du respect des lois am\u00e9ricaines et \u00e9trang\u00e8res en mati\u00e8re de commerce et de fiscalit\u00e9, des sanctions, des embargos et autres r\u00e9glementations&nbsp;; (m)&nbsp;les cons\u00e9quences des \u00e9v\u00e9nements impr\u00e9vus, dont les poursuites judiciaires, enqu\u00eates gouvernementales ou r\u00e9glementaires et mesures d\u2019assainissement de l\u2019environnement, qui peuvent exposer Howmet Aerospace \u00e0 des co\u00fbts et responsabilit\u00e9s substantiels&nbsp;; (n)&nbsp;le non-respect de la r\u00e9glementation publique des march\u00e9s&nbsp;; (o)&nbsp;les fluctuations d\u00e9favorables des taux d\u2019actualisation ou du rendement des placements des actifs de retraite&nbsp;; et (p)&nbsp;les autres facteurs de risque r\u00e9sum\u00e9s dans le formulaire&nbsp;10-K de Howmet Aerospace relatif \u00e0 l\u2019exercice clos le 31&nbsp;d\u00e9cembre&nbsp;2022 et dans d\u2019autres rapports d\u00e9pos\u00e9s aupr\u00e8s de la Securities and Exchange Commission des \u00c9tats-Unis. Les projections de march\u00e9 sont soumises aux risques d\u00e9crits ci-dessus et aux autres risques du march\u00e9. Les D\u00e9clarations figurant dans toute pr\u00e9sentation ou tout document sont effectu\u00e9es \u00e0 la date de ladite pr\u00e9sentation ou dudit document. Howmet Aerospace d\u00e9cline toute intention ou obligation de mettre \u00e0 jour publiquement les d\u00e9clarations prospectives, que ce soit en r\u00e9ponse \u00e0 de nouvelles informations, \u00e0 des \u00e9v\u00e9nements futurs ou autrement, sauf si requis par la loi applicable.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-alcoa-wheels-card-usecase-1 card-box-v1__body with-icon align-center vertical-align-center\" id=\"card_box_v1-941056e7-24d3-499f-8ff3-90c3020b062e\"><div class=\"fullwidthcontainer\"><div class=\"card-box-v1__boxes has-4-columns\"><div class=\"card-box-v1__box  with-link \" style=\"background-color:#00afb9\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"Contactez-nous\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"171\" height=\"171\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/contact.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">Contactez-nous<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/contact\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#34bfc7\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"Gamme de roues\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/product-search.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">Gamme de roues<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/gamme-de-roues\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#00afb9\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"O\u00f9 acheter?\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/where-to-buy.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">O\u00f9 acheter?<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/ou-acheter\"><\/a><\/div><div class=\"card-box-v1__box  with-link \" style=\"background-color:#34bfc7\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/themes\/alcoa-wheels\/assets\/build\/js\/blocks\/card-usecase-1\/..\/..\/..\/images\/placeholder-image.db2b4d5c.jpeg\" alt=\"T\u00e9l\u00e9chargements\"\/><div class=\"card-box-v1__box__inner pos-abs\"><div class=\"card-box-v1__box_icon\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"169\" src=\"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/06\/product-literature.png\" alt=\"\"\/><\/div><div class=\"card-box-v1__box_content\"><h4 style=\"color:#ffffff\">T\u00e9l\u00e9chargements<\/h4><\/div><div class=\"btn-wrap\"><\/div><\/div><a href=\"\/europe\/fr\/documents-produit\"><\/a><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales en ligne de Howmet Aerospace Howmet Aerospace Inc. et ses filiales et soci\u00e9t\u00e9s affili\u00e9es (ci-apr\u00e8s, collectivement \u00ab&nbsp;Howmet Aerospace&nbsp;\u00bb) maintiennent ce site Web \u00e0 des fins d&#8217;information, d&#8217;\u00e9ducation et de communication. Sauf indication contraire, vous pouvez t\u00e9l\u00e9charger le mat\u00e9riel affich\u00e9 sur ce site Web pour un usage non commercial et personnel uniquement, \u00e0 condition [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"protected_reviewer_email":"","editor_notices":[],"footnotes":""},"class_list":["post-66","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mentions l\u00e9gales en ligne de Howmet Aerospace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis juridique\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales en ligne de Howmet Aerospace Howmet Aerospace Inc. et ses filiales et soci\u00e9t\u00e9s affili\u00e9es (ci-apr\u00e8s, collectivement \u00ab&nbsp;Howmet Aerospace&nbsp;\u00bb) maintiennent ce site Web \u00e0 des fins d&#8217;information, d&#8217;\u00e9ducation et de communication. Sauf indication contraire, vous pouvez t\u00e9l\u00e9charger le mat\u00e9riel affich\u00e9 sur ce site Web pour un usage non commercial et personnel uniquement, \u00e0 condition [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe French\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T08:48:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/\",\"name\":\"Mentions l\u00e9gales en ligne de Howmet Aerospace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#website\"},\"datePublished\":\"2023-05-26T06:43:04+00:00\",\"dateModified\":\"2023-08-24T08:48:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis juridique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\",\"name\":\"Europe French\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#organization\",\"name\":\"Europe French\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/05\\\/logo-black.gif\",\"contentUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/05\\\/logo-black.gif\",\"width\":71,\"height\":64,\"caption\":\"Europe French\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales en ligne de Howmet Aerospace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","og_locale":"en_US","og_type":"article","og_title":"Avis juridique","og_description":"Mentions l\u00e9gales en ligne de Howmet Aerospace Howmet Aerospace Inc. et ses filiales et soci\u00e9t\u00e9s affili\u00e9es (ci-apr\u00e8s, collectivement \u00ab&nbsp;Howmet Aerospace&nbsp;\u00bb) maintiennent ce site Web \u00e0 des fins d&#8217;information, d&#8217;\u00e9ducation et de communication. Sauf indication contraire, vous pouvez t\u00e9l\u00e9charger le mat\u00e9riel affich\u00e9 sur ce site Web pour un usage non commercial et personnel uniquement, \u00e0 condition [&hellip;]","og_url":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","og_site_name":"Europe French","article_modified_time":"2023-08-24T08:48:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","name":"Mentions l\u00e9gales en ligne de Howmet Aerospace","isPartOf":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#website"},"datePublished":"2023-05-26T06:43:04+00:00","dateModified":"2023-08-24T08:48:03+00:00","breadcrumb":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alcoawheels.com\/europe\/fr\/"},{"@type":"ListItem","position":2,"name":"Avis juridique"}]},{"@type":"WebSite","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#website","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/","name":"Europe French","description":"","publisher":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alcoawheels.com\/europe\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#organization","name":"Europe French","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/logo-black.gif","contentUrl":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-content\/uploads\/sites\/15\/2023\/05\/logo-black.gif","width":71,"height":64,"caption":"Europe French"},"image":{"@id":"https:\/\/www.alcoawheels.com\/europe\/fr\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/alcoawheels.com\/europe\/fr\/mentions-legales\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Avis juridique","url":"http:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.alcoawheels.com\/europe\/fr\/mentions-legales\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"howmet"}],"creator":["howmet"],"publisher":{"@type":"Organization","name":"Europe French","logo":""},"keywords":[],"dateCreated":"2023-05-26T06:43:04Z","datePublished":"2023-05-26T06:43:04Z","dateModified":"2023-08-24T08:48:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"WebPage\",\"headline\":\"Avis juridique\",\"url\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/fr\\\/mentions-legales\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"howmet\"}],\"creator\":[\"howmet\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Europe French\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-05-26T06:43:04Z\",\"datePublished\":\"2023-05-26T06:43:04Z\",\"dateModified\":\"2023-08-24T08:48:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/alcoawheels.com\/p.js"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":8,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/66\/revisions"}],"predecessor-version":[{"id":1573,"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/pages\/66\/revisions\/1573"}],"wp:attachment":[{"href":"https:\/\/www.alcoawheels.com\/europe\/fr\/wp-json\/wp\/v2\/media?parent=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}