{"id":2219,"date":"2024-07-19T17:41:32","date_gmt":"2024-07-19T14:41:32","guid":{"rendered":"https:\/\/www.alcoawheels.com\/europe\/tr\/?page_id=2219"},"modified":"2024-10-07T18:42:48","modified_gmt":"2024-10-07T15:42:48","slug":"mukavemet-testi","status":"publish","type":"page","link":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","title":{"rendered":"Mukavemet Testi"},"content":{"rendered":"\n<div class=\"wp-block-alcoa-wheels-hero-banner-innerpage hero-banner with-image layout-2 overlayEnable align- vertical-align- align-center vertical-align-center\" style=\"background-color:#eee\"><img decoding=\"async\" src=\"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg\" alt=\"Why Alcoa Wheels\" class=\"responsiveImage\"\/><div class=\"hero-banner__header\" style=\"text-align:center\"><div class=\"container\"><h1 class=\"hero-banner__header--title\">Mukavemet Testi<\/h1><\/div><\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer spacer-fifty\"><\/div>\n\n\n\n<p>Alcoa<sup>\u00ae<\/sup> Ultra ONE<sup>\u00ae<\/sup> jant 22,5&#8243; x 9,00&#8243; (par\u00e7a numaras\u0131 89U520) 442 kN \/ 45076 kg alt\u0131nda 50 mm deforme olarak ayn\u0131 boyuttaki Maxion \u00e7elik janta (par\u00e7a numaras\u0131 2920841) k\u0131yasla 3,4 kat daha g\u00fc\u00e7l\u00fc performans g\u00f6stererek 129 kN \/ 13154 kg kuvvet alt\u0131nda 50 mm deforme olmu\u015ftur.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" height=\"569\" width=\"1024\" src=\"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?w=1024\" alt=\"\" class=\"wp-image-2221\" style=\"width:881px\" srcset=\"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png 4266w, https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?resize=300,167 300w, https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?resize=768,427 768w, https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?resize=1024,569 1024w, https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?resize=1536,854 1536w, https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2024\/07\/Alcoa-vs.-Steel-high-resolution.png?resize=2048,1139 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Mukavemet Testi &#8211; Sz\u00e9chenyi Istv\u00e1n \u00dcniversitesi, Ara\u00e7 \u00dcretimi ve Teknolojisi B\u00f6l\u00fcm\u00fc, Macaristan, 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcoa\u00ae Ultra ONE\u00ae jant 22,5&#8243; x 9,00&#8243; (par\u00e7a numaras\u0131 89U520) 442 kN \/ 45076 kg alt\u0131nda 50 mm deforme olarak ayn\u0131 boyuttaki Maxion \u00e7elik janta (par\u00e7a numaras\u0131 2920841) k\u0131yasla 3,4 kat daha g\u00fc\u00e7l\u00fc performans g\u00f6stererek 129 kN \/ 13154 kg kuvvet alt\u0131nda 50 mm deforme olmu\u015ftur. Mukavemet Testi &#8211; Sz\u00e9chenyi Istv\u00e1n \u00dcniversitesi, Ara\u00e7 \u00dcretimi ve [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"protected_reviewer_email":"","editor_notices":[],"footnotes":""},"class_list":["post-2219","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mukavemet Testi - Europe Turkish<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mukavemet Testi\" \/>\n<meta property=\"og:description\" content=\"Alcoa\u00ae Ultra ONE\u00ae jant 22,5&#8243; x 9,00&#8243; (par\u00e7a numaras\u0131 89U520) 442 kN \/ 45076 kg alt\u0131nda 50 mm deforme olarak ayn\u0131 boyuttaki Maxion \u00e7elik janta (par\u00e7a numaras\u0131 2920841) k\u0131yasla 3,4 kat daha g\u00fc\u00e7l\u00fc performans g\u00f6stererek 129 kN \/ 13154 kg kuvvet alt\u0131nda 50 mm deforme olmu\u015ftur. Mukavemet Testi &#8211; Sz\u00e9chenyi Istv\u00e1n \u00dcniversitesi, Ara\u00e7 \u00dcretimi ve [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe Turkish\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T15:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/\",\"name\":\"Mukavemet Testi - Europe Turkish\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/06\\\/benefits-banner.jpeg\",\"datePublished\":\"2024-07-19T14:41:32+00:00\",\"dateModified\":\"2024-10-07T15:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/06\\\/benefits-banner.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/06\\\/benefits-banner.jpeg\",\"width\":1119,\"height\":280,\"caption\":\"Why Alcoa Wheels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mukavemet Testi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/\",\"name\":\"Europe Turkish\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#organization\",\"name\":\"Europe Turkish\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/05\\\/logo-black.gif\",\"contentUrl\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/05\\\/logo-black.gif\",\"width\":71,\"height\":64,\"caption\":\"Europe Turkish\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mukavemet Testi - Europe Turkish","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","og_locale":"en_US","og_type":"article","og_title":"Mukavemet Testi","og_description":"Alcoa\u00ae Ultra ONE\u00ae jant 22,5&#8243; x 9,00&#8243; (par\u00e7a numaras\u0131 89U520) 442 kN \/ 45076 kg alt\u0131nda 50 mm deforme olarak ayn\u0131 boyuttaki Maxion \u00e7elik janta (par\u00e7a numaras\u0131 2920841) k\u0131yasla 3,4 kat daha g\u00fc\u00e7l\u00fc performans g\u00f6stererek 129 kN \/ 13154 kg kuvvet alt\u0131nda 50 mm deforme olmu\u015ftur. Mukavemet Testi &#8211; Sz\u00e9chenyi Istv\u00e1n \u00dcniversitesi, Ara\u00e7 \u00dcretimi ve [&hellip;]","og_url":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","og_site_name":"Europe Turkish","article_modified_time":"2024-10-07T15:42:48+00:00","og_image":[{"url":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","url":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","name":"Mukavemet Testi - Europe Turkish","isPartOf":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/#primaryimage"},"image":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg","datePublished":"2024-07-19T14:41:32+00:00","dateModified":"2024-10-07T15:42:48+00:00","breadcrumb":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/#primaryimage","url":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg","contentUrl":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/06\/benefits-banner.jpeg","width":1119,"height":280,"caption":"Why Alcoa Wheels"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alcoawheels.com\/europe\/tr\/"},{"@type":"ListItem","position":2,"name":"Mukavemet Testi"}]},{"@type":"WebSite","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#website","url":"https:\/\/www.alcoawheels.com\/europe\/tr\/","name":"Europe Turkish","description":"","publisher":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alcoawheels.com\/europe\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#organization","name":"Europe Turkish","url":"https:\/\/www.alcoawheels.com\/europe\/tr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/05\/logo-black.gif","contentUrl":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-content\/uploads\/sites\/24\/2023\/05\/logo-black.gif","width":71,"height":64,"caption":"Europe Turkish"},"image":{"@id":"https:\/\/www.alcoawheels.com\/europe\/tr\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/alcoawheels.com\/europe\/tr\/mukavemet-testi\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Mukavemet Testi","url":"http:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.alcoawheels.com\/europe\/tr\/mukavemet-testi\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"riccirm"}],"creator":["riccirm"],"publisher":{"@type":"Organization","name":"Europe Turkish","logo":""},"keywords":[],"dateCreated":"2024-07-19T14:41:32Z","datePublished":"2024-07-19T14:41:32Z","dateModified":"2024-10-07T15:42:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"WebPage\",\"headline\":\"Mukavemet Testi\",\"url\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.alcoawheels.com\\\/europe\\\/tr\\\/mukavemet-testi\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"riccirm\"}],\"creator\":[\"riccirm\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Europe Turkish\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-19T14:41:32Z\",\"datePublished\":\"2024-07-19T14:41:32Z\",\"dateModified\":\"2024-10-07T15:42:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/alcoawheels.com\/p.js"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/pages\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":3,"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/pages\/2219\/revisions"}],"predecessor-version":[{"id":2252,"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/pages\/2219\/revisions\/2252"}],"wp:attachment":[{"href":"https:\/\/www.alcoawheels.com\/europe\/tr\/wp-json\/wp\/v2\/media?parent=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}